{"id":477,"date":"2020-01-31T13:39:52","date_gmt":"2020-01-31T12:39:52","guid":{"rendered":"https:\/\/cicloturistalacubilla.es\/avis-juridique\/"},"modified":"2020-12-29T08:05:10","modified_gmt":"2020-12-29T07:05:10","slug":"avis-juridique","status":"publish","type":"page","link":"https:\/\/cicloturistalacubilla.es\/fr\/avis-juridique\/","title":{"rendered":"Avis Juridique"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"477\" class=\"elementor elementor-477 elementor-319\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-bb79ae8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb79ae8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b9cbd0\" data-id=\"4b9cbd0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35d5ba2 elementor-widget elementor-widget-shortcode\" data-id=\"35d5ba2\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\n<h2>Identificaci\u00f3n y Titularidad<\/h2>\n\n<p>\n\t\tEn cumplimiento del art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y Comercio Electr\u00f3nico, el Titular expone sus datos identificativos:\n<\/p>\n\n<p>\n\t<ul>\t\t\n\t\t<li>\n\t\t\t<b>Titular:<\/b>&nbsp;\t\t\n\t\t\tClub Actitude.\n\t\t\t\n\t\t<\/li>\n\t\t\n\t\t<li>\n\t\t\t<b>NIF:<\/b>&nbsp;G67884809\n\t\t\t\n\t\t<\/li>\n\n\n\t\t<li>\n\t\t\t<b>Domicilio:<\/b>&nbsp;\n\t\t\t Camino de la Candelaria 77,  Asturias - Espa\u00f1a.\n\t\t<\/li>\n\t\t\n\t\t<li>\n\t\t\t<b>Correo electr\u00f3nico:<\/b>&nbsp;\n\t\t\tinfo@actitudeeventos.es\n\t\t<\/li>\n\t\t\n\n\t\t<li>\n\t\t\t<b>Sitio Web:<\/b>&nbsp;\n\t\t\t<a href=\"https:\/\/cicloturistalacubilla.es\">https:\/\/cicloturistalacubilla.es<\/a>\n\t\t<\/li>\n\t<\/ul>\n<\/p>\n\n<h2>Finalidad<\/h2>\n<p>\n\tLa finalidad del Sitio Web es: Evento Deportivo.\t\n<\/p>\n\n\n<h2>Condiciones de Uso<\/h2>\n<p>\n\tLa utilizaci\u00f3n del Sitio Web le otorga la condici\u00f3n de Usuario, e implica la aceptaci\u00f3n completa de todas las cl\u00e1usulas y condiciones de uso incluidas en las p\u00e1ginas:\n\t<ul>\t\t\n\t\t<li><a href=\"https:\/\/cicloturistalacubilla.es\/fr\/avis-juridique\/\">Aviso Legal<\/a><\/li>\n\t\t<li><a href=\"https:\/\/cicloturistalacubilla.es\/fr\/politique-de-confidentialite\/\">Pol\u00edtica de Privacidad<\/a><\/li>\n\t\t\n\t<\/ul>\t\n<\/p>\n\n<p>\n\tSi no estuviera conforme con todas y cada una de estas cl\u00e1usulas y condiciones abst\u00e9ngase de utilizar el Sitio Web.\n<\/p>\n\n<p>\t\n\tEl acceso al Sitio Web no supone, en modo alguno, el inicio de una relaci\u00f3n comercial con el Titular.\n<\/p>\n\n<p>\t\n\tA trav\u00e9s del Sitio Web, el Titular le facilita el acceso y la utilizaci\u00f3n de diversos contenidos que el Titular y\/o sus colaboradores han publicado por medio de Internet.\n<\/p>\n\n<p>\n\tA tal efecto, est\u00e1 obligado y comprometido a NO utilizar cualquiera de los contenidos del Sitio Web con fines o efectos il\u00edcitos, prohibidos en este Aviso Legal o por la legislaci\u00f3n vigente, lesivos de los derechos e intereses de terceros, o que de cualquier forma puedan da\u00f1ar, inutilizar, sobrecargar, deteriorar o impedir la normal utilizaci\u00f3n de los contenidos, los equipos inform\u00e1ticos o los documentos, archivos y toda clase de contenidos almacenados en cualquier equipo inform\u00e1tico propios o contratados por el Titular, de otros usuarios o de cualquier usuario de Internet.\n<\/p>\n\n\n\n\n\n\n<h2>Medidas de seguridad<\/h2>\n<p>\n\tLos datos personales que facilite al Titular pueden ser almacenados en bases de datos automatizadas o no, cuya titularidad corresponde en exclusiva al Titular, que asume todas las medidas de \u00edndole t\u00e9cnica, organizativa y de seguridad que garantizan la confidencialidad, integridad y calidad de la informaci\u00f3n contenida en las mismas de acuerdo con lo establecido en la normativa vigente en protecci\u00f3n de datos.\n<\/p>\n<p>\n\tNo obstante, debe ser consciente de que las medidas de seguridad de los sistemas inform\u00e1ticos en Internet no son enteramente fiables y que, por tanto el Titular no puede garantizar la inexistencia de virus u otros elementos que puedan producir alteraciones en los sistemas inform\u00e1ticos (software y hardware) del Usuario o en sus documentos electr\u00f3nicos y ficheros contenidos en los mismos aunque el Titular pone todos los medios necesarios y toma las medidas de seguridad oportunas para evitar la presencia de estos elementos da\u00f1inos.\n<\/p>\n\n\n<h2>Tratamiento de Datos Personales<\/h2>\n<p>\t\n\tPuede consultar toda la informaci\u00f3n relativa al tratamiento de datos personales que recoge el Titular en la p\u00e1gina de  <a href=\"https:\/\/cicloturistalacubilla.es\/fr\/politique-de-confidentialite\/\">Pol\u00edtica de Privacidad<\/a>.\n<\/p>\n\n<h2>Contenidos<\/h2>\n<p>\n\tEl Titular ha obtenido la informaci\u00f3n, el contenido multimedia y los materiales incluidos en el Sitio Web de fuentes que considera fiables, pero, si bien ha tomado todas las medidas razonables para asegurar que la informaci\u00f3n contenida es correcta, el Titular no garantiza que sea exacta, completa o actualizada. El Titular declina expresamente cualquier responsabilidad por error u omisi\u00f3n en la informaci\u00f3n contenida en las p\u00e1ginas del Sitio Web.\n<\/p>\n\n<p>\n\tQueda prohibido transmitir o enviar a trav\u00e9s del Sitio Web cualquier contenido ilegal o il\u00edcito, virus inform\u00e1ticos, o mensajes que, en general, afecten o violen derechos del Titular o de terceros.\n<\/p>\n\n<p>\n\tLos contenidos del Sitio Web tienen \u00fanicamente una finalidad informativa y bajo ninguna circunstancia deben usarse ni considerarse como oferta de venta, solicitud de una oferta de compra ni recomendaci\u00f3n para realizar cualquier otra operaci\u00f3n, salvo que as\u00ed se indique expresamente.\n<\/p>\n\n<p>\n\tEl Titular se reserva el derecho a modificar, suspender, cancelar o restringir el contenido del Sitio Web, los v\u00ednculos o la informaci\u00f3n obtenida a trav\u00e9s del Sitio Web, sin necesidad de previo aviso.\n<\/p>\n\n<p>\n\tEl Titular\u00a0no es responsable de los da\u00f1os y perjuicios que pudieran derivarse de la utilizaci\u00f3n de la informaci\u00f3n del Sitio Web o de la contenida en las redes sociales del Titular.\n<\/p>\n\n\n<h2>Pol\u00edtica de cookies<\/h2>\n<p>\n\tEl Titular obtiene y conserva la siguiente informaci\u00f3n acerca de los visitantes del Sitio Web:\n<\/p>\n<p>\n\t<ul>\n\t\t<li>El nombre de dominio del proveedor (PSI) y\/o direcci\u00f3n IP que les da acceso a la red.<\/li>\n\t\t<li>La fecha y hora de acceso al sitio Web.<\/li>\n\t\t<li>La direcci\u00f3n de Internet origen del enlace que dirige al sitio Web.<\/li>\n\t\t<li>El n\u00famero de visitantes diarios de cada secci\u00f3n.<\/li>\n\t\t<li>La informaci\u00f3n obtenida es totalmente an\u00f3nima, y en ning\u00fan caso puede ser asociada a un Usuario concreto e identificado.<\/li>\n\t<\/ul>\n<\/p>\n\n\n<h2>Enlaces a otros sitios Web<\/h2>\n<p>\n\tEl Titular puede proporcionarle acceso a sitios Web de terceros mediante enlaces con la finalidad exclusiva de informar sobre la existencia de otras fuentes de informaci\u00f3n en Internet en las que podr\u00e1 ampliar los datos ofrecidos en el Sitio Web.\n<\/p>\n\n<p>\t\n\tEstos enlaces a otros sitios Web no suponen en ning\u00fan caso una sugerencia o recomendaci\u00f3n para que usted visite las p\u00e1ginas web de destino, que est\u00e1n fuera del control del Titular, por lo que el Titular no es responsable del contenido de los sitios web vinculados ni del resultado que obtenga al seguir los enlaces.\n\tAsimismo, el Titular no responde de los links o enlaces ubicados en los sitios web vinculados a los que le proporciona acceso.\n<\/p>\n\n<p>\n\tEl establecimiento del enlace no implica en ning\u00fan caso la existencia de relaciones entre el Titular y el propietario del sitio en el que se establezca el enlace, ni la aceptaci\u00f3n o aprobaci\u00f3n por parte del Titular de sus contenidos o servicios.\n<\/p>\n\n<p>\t\n\tSi accede a un sitio web externo desde un enlace que encuentre en el Sitio Web usted deber\u00e1 leer la propia pol\u00edtica de privacidad del otro sitio web que puede ser diferente de la de este sitio Web.\n<\/p>\n\n\n\n<h2>Propiedad intelectual e industrial<\/h2>\n<p>\n\tTodos los derechos est\u00e1n reservados.\n<\/p>\n<p>\n\tTodo acceso a este Sitio Web est\u00e1 sujeto a las siguientes condiciones: la reproducci\u00f3n, almacenaje permanente y la difusi\u00f3n de los contenidos o cualquier otro uso que tenga finalidad p\u00fablica o comercial queda expresamente prohibida sin el consentimiento previo expreso y por escrito del Titular.\n<\/p>\n\n\n<h2>Limitaci\u00f3n de responsabilidad<\/h2>\n<p>\n\tLa informaci\u00f3n y servicios incluidos o disponibles a trav\u00e9s del Sitio Web pueden incluir incorrecciones o errores tipogr\u00e1ficos. De forma peri\u00f3dica el Titular incorpora mejoras y\/o cambios a la informaci\u00f3n contenida y\/o los Servicios que puede introducir en cualquier momento.\n<\/p>\n<p>\n\tEl Titular no declara ni garantiza que los servicios o contenidos sean interrumpidos o que est\u00e9n libres de errores, que los defectos sean corregidos, o que el servicio o el servidor que lo pone a disposici\u00f3n est\u00e9n libres de virus u otros componentes nocivos sin perjuicio de que el Titular realiza todos los esfuerzos en evitar este tipo de incidentes.\n<\/p>\n<p>\n\tEl Titular declina cualquier responsabilidad en caso de que existan interrupciones o un mal funcionamiento de los Servicios o contenidos ofrecidos en Internet, cualquiera que sea su causa. Asimismo, el Titular no se hace responsable por ca\u00eddas de la red, p\u00e9rdidas de negocio a consecuencia de dichas ca\u00eddas, suspensiones temporales de fluido el\u00e9ctrico o cualquier otro tipo de da\u00f1o indirecto que te pueda ser causado por causas ajenas a el Titular.\n<\/p>\n<p>\n\tAntes de tomar decisiones y\/o acciones con base a la informaci\u00f3n incluida en el Sitio Web, el Titular le recomienda comprobar y contrastar la informaci\u00f3n recibida con otras fuentes.\n<\/p>\n\n\n\n<h2>Jurisdicci\u00f3n<\/h2>\n<p>\t\n\tEste Aviso Legal se rige \u00edntegramente por la legislaci\u00f3n espa\u00f1ola.\n<\/p>\n\n\n<h2>Contacto<\/h2>\n<p>\t\n\tEn caso de que usted tenga cualquier duda acerca de este Aviso Legal o quiera realizar cualquier comentario sobre el Sitio Web, puede enviar un mensaje de correo electr\u00f3nico a la direcci\u00f3n: info@actitudeeventos.es\n<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-477","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/cicloturistalacubilla.es\/fr\/wp-json\/wp\/v2\/pages\/477"}],"collection":[{"href":"https:\/\/cicloturistalacubilla.es\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cicloturistalacubilla.es\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cicloturistalacubilla.es\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cicloturistalacubilla.es\/fr\/wp-json\/wp\/v2\/comments?post=477"}],"version-history":[{"count":0,"href":"https:\/\/cicloturistalacubilla.es\/fr\/wp-json\/wp\/v2\/pages\/477\/revisions"}],"wp:attachment":[{"href":"https:\/\/cicloturistalacubilla.es\/fr\/wp-json\/wp\/v2\/media?parent=477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}